{"id":1115,"date":"2022-11-24T14:06:38","date_gmt":"2022-11-24T14:06:38","guid":{"rendered":"https:\/\/fratellilaise.com\/main\/?post_type=product&#038;p=1115"},"modified":"2024-09-15T08:19:53","modified_gmt":"2024-09-15T08:19:53","slug":"liquore-crema-di-limone-bio-500-ml","status":"publish","type":"product","link":"https:\/\/fratellilaise.com\/main\/product\/liquore-crema-di-limone-bio-500-ml\/","title":{"rendered":"Liquore Crema di Limone BIO 500 ml"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Liquore Crema di Limone BIO, vol.17%<\/p>\n<p>Liquore ottenuto secondo una ricetta tradizionale che utilizza ingredienti di prima scelta.<\/p>\n<p>Ingredienti: Latte parzialmente scremato, alcol idrato puro, zucchero di canna, destrosio, infuso di scorze di limone, miele di zagara, burro di cacao, vaniglia. Stabilizzante: farina di semi di carruba. Pu\u00f2 contenere tracce di frutta secca a guscio, sesamo.<\/p>\n<p>Al fine di migliorare aroma e gusto agitare bene prima dell&#8217;uso per rimettere in sospensione il naturale sedimento.<\/p>\n<p>Il liquore pu\u00f2 presentare naturali sedimenti che si depositano sul fondo o che affiorino a galla, il tutto a garanzia della qualit\u00e0 del prodotto.<\/p>\n<p>Prodotto e imbottigliato da: La Ferrera Antonio a Gagliano Castelferrato (EN) ITALIA.<\/p>\n","protected":false},"featured_media":1148,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[64],"product_tag":[],"class_list":{"0":"post-1115","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-liquori","8":"first","9":"instock","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/fratellilaise.com\/main\/wp-json\/wp\/v2\/product\/1115","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fratellilaise.com\/main\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/fratellilaise.com\/main\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/fratellilaise.com\/main\/wp-json\/wp\/v2\/comments?post=1115"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fratellilaise.com\/main\/wp-json\/wp\/v2\/media\/1148"}],"wp:attachment":[{"href":"https:\/\/fratellilaise.com\/main\/wp-json\/wp\/v2\/media?parent=1115"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/fratellilaise.com\/main\/wp-json\/wp\/v2\/product_brand?post=1115"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/fratellilaise.com\/main\/wp-json\/wp\/v2\/product_cat?post=1115"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/fratellilaise.com\/main\/wp-json\/wp\/v2\/product_tag?post=1115"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}